{"id":37174,"date":"2020-09-09T12:47:02","date_gmt":"2020-09-09T12:47:02","guid":{"rendered":"https:\/\/furnitureroots.com\/?page_id=37174"},"modified":"2021-08-17T12:41:08","modified_gmt":"2021-08-17T12:41:08","slug":"modern-style","status":"publish","type":"page","link":"https:\/\/furnitureroots.com\/it\/arredi-per-ristoranti\/stile-moderno\/","title":{"rendered":"Mobili da ristorante moderni"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"section-element vc_custom_1623236639186 vc_row-has-fill\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h1 style=\"font-size: 28px;color: #333333;text-align: center\" class=\"vc_custom_heading vc_custom_1625205932205\">ARREDO RISTORANTE MODERNO E CONTEMPORANEO<\/h1><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html row-1\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<nav class=\"rep-field-breadcrumbs\">\n     <a href=\"https:\/\/furnitureroots.com\/it\/\">\t\n       <span>Casa \/<\/span> <\/a>\t\t\t\t\t\t\t\n     <\/a>\n     <a href=\"https:\/\/furnitureroots.com\/it\/restaurant-furniture\/\">\t\t\t\t\t\t\t<span>Mobili per ristoranti \/<\/span> <\/a>\n <\/a>\n     <a href=\"https:\/\/furnitureroots.com\/it\/restaurant-furniture\/modern-style\/\">\t\t\t\t\t\t\t<span>Mobili da ristorante moderni<\/span> <\/a>\n  \n     <\/a>\n<\/nav>\n\n<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\\\/\",\n    \"@type\": \"BreadcrumbList\",\n    \"itemListElement\": [\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 1,\n            \"name\": \"Home\",\n            \"item\": \"https:\\\/\\\/furnitureroots.com\\\/\"\n        },\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 2,\n            \"name\": \"Restaurant Furniture\",\n            \"item\": \"https:\\\/\\\/furnitureroots.com\\\/restaurant-furniture\\\/\"\n        },\n        {\n            \"@type\": \"ListItem\",\n            \"position\": 3,\n            \"name\": \"Modern Restaurant Furniture\",\n            \"item\": \"https:\\\/\\\/furnitureroots.com\\\/restaurant-furniture\\\/modern-style\\\/\"\n        }\n    ]\n}<\/script>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div style=\"text-align: justify;\">\n<p class=\"translation-block\"><span style=\"font-size: 10pt\">I nostri mobili da ristorante moderni contrastano con i nostri mobili da ristorante a tema classico in quanto di solito presentano linee pi\u00f9 nitide, finiture vivaci e funzionalit\u00e0 elegante. I mobili in stile moderno sono eleganti, durevoli e coprono l&#039;intera gamma di colori che vanno dai toni ai vivaci. I nostri set da bistrot contemporanei e moderni, sedie, separ\u00e9 e tavoli per ristoranti sono buoni esempi dello stile di design moderno. Ottieni mobili moderni su misura a prezzi all&#039;ingrosso direttamente da un <a href=\"\/it\/restaurant-furniture\/\" target=\"_blank\" rel=\"noopener noreferrer\">produttore di mobili per ristoranti<\/a> specializzati: FurnitureRoots.<br><\/span><\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f36373-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"36373\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/37174#wpcf7-f36373-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/37174#wpcf7-f36373-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"36373\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f36373-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-row dashingform\">\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome: Jon Doe\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail: Jon@gmail.com\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"country\"><option value=\"\">Seleziona il paese<\/option><option value=\"Australia\">Australia<\/option><option value=\"Brazil\">Brasile<\/option><option value=\"Canada\">Canada<\/option><option value=\"Chile\">Chile<\/option><option value=\"Dubai\">Dubai<\/option><option value=\"France\">Francia<\/option><option value=\"Germany\">Germania<\/option><option value=\"India\">India<\/option><option value=\"Italy\">Italia<\/option><option value=\"Netherlands\">Olanda<\/option><option value=\"Portugal\">Portogallo<\/option><option value=\"Russia\">Russia<\/option><option value=\"Saudi Arabia\">Arabia Saudita<\/option><option value=\"South Africa\">Sud Africa<\/option><option value=\"Spain\">Spagna<\/option><option value=\"United Kingdom\">Regno Unito<\/option><option value=\"United States\">stati Uniti<\/option><option value=\"Other\">Altro<\/option><\/select><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"Contact\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel cf71\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono: 00000011\" value=\"\" type=\"tel\" name=\"Contact\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-Message\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Parlaci del tuo progetto\" value=\"\" type=\"text\" name=\"your-Message\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">Please prove you are human by selecting the<span> car<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M512 176a176 176 0 01-209 173l-24 27a24 24 0 01-18 8h-37v40c0 13-11 24-24 24h-40v40c0 13-11 24-24 24H24c-13 0-24-11-24-24v-78c0-6 3-13 7-17l162-162a176 176 0 11343-55zm-176-48a48 48 0 1096 0 48 48 0 00-96 0z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t<\/p>\n\t<div class=\"grid-20\">\n\t\t<p><label id=\"contact-form-click\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Ottieni assistenza da esperti\" \/><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Pianifica un momento adatto per una chiamata con il nostro esperto di mobili!<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"section-element vc_custom_1598099559805 vc_row-no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html vc_custom_1599848111354\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<a href=\"https:\/\/furnitureroots.com\/it\/contact-us\/\">\n<div class=\"row row-1\">\n<img decoding=\"async\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/Commercial-Grade-1.png\" style=\"width:100%;\">\n<\/div>\n<\/a>\n\n<style>\n.row-1{\nmargin: auto;\n    margin-top: auto;\n    margin-bottom: auto;\nwidth: 100% !important;\nmargin-top: auto;\nmargin-bottom: auto;\ntext-align: center;}\n<\/style>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">CATEGORIE DI MOBILI MODERNI<\/h2><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"color: #333333;\"><a style=\"color: #333333;\" href=\"\/it\/c\/restaurant-chairs\/attribute-style-modern\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 12pt;\"><strong>SEDIE MODERNE DEL RISTORANTE<\/strong><\/span><\/a><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-chairs\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img fetchpriority=\"high\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Restaurant-Tub-Dining-Chair.png\" width=\"300\" height=\"300\" alt=\"sedia a pozzetto in stile moderno per cene di ristoranti commerciali\" title=\"Sedia da pranzo moderna per vasca da ristorante\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\" class=\"translation-block\"><span style=\"font-size: 10pt\">Trova sedie contemporanee che offrono comfort e individualit\u00e0 senza pari al tuo caff\u00e8, bar o bistrot. Dai un&#039;occhiata anche ai nostri <a href=\"\/it\/c\/restaurant-bar-stools\/attribute-style-modern\/\" target=\"_self\">sgabelli da bar in stile moderno per uso ristorante<\/a> .<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333;\"><span style=\"font-size: 12pt;\"><strong>SCOPRI LE SEDIE DA PRANZO<\/strong><\/span><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"color: #333333;\"><a style=\"color: #333333;\" href=\"\/it\/c\/restaurant-booths\/attribute-style-modern\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 12pt;\"><strong>CABINE RISTORANTI MODERNE<\/strong><\/span><\/a><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-booths\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Navy-Blue-Restaurant-Dining-Booth.png\" width=\"300\" height=\"300\" alt=\"cabina da pranzo blu navy, cucita a mano\" title=\"Cabina da pranzo del ristorante blu navy\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Esplora i moderni posti a sedere in un ristorante. Forniamo cabine ristorante in legno, panche a muro e sedute angolari realizzate su misura per adattarsi all&#039;arredamento e all&#039;atmosfera di qualsiasi spazio<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333;\"><span style=\"font-size: 12pt;\"><strong>SCOPRI I POSTI DELLO STAND<\/strong><\/span><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #da8a67;\"><span style=\"color: #333333;\">TAVOLI MODERNI DEL RISTORANTE<\/span><\/span><\/strong><\/span><\/a><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Wooden-Mid-Century-Dining-Table.png\" width=\"300\" height=\"300\" alt=\"tavolo da ristorante moderno di met\u00e0 secolo\" title=\"Tavolo da pranzo moderno in legno di met\u00e0 secolo\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Scopri tavoli da ristorante contemporanei in legno, tavoli da pranzo ad altezza bar, tavoli in metallo e tavoli da bistrot da esterno per ristoranti, comprese basi e piani per tavoli in design unici\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #da8a67;\"><span style=\"color: #333333;\">SCOPRI I TAVOLI DA PRANZO<\/span><\/span><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"section-element vc_custom_1598099559805 vc_row-no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">ALCUNI DEI NOSTRI PRODOTTI D&#039;ARREDO PER RISTORANTI MODERNI<\/h2><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-chairs\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/FRRSEAT0921-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Panca a muro altezza bar imbottita in tessuto trapuntato con bottoni con corrimano e dettaglio chiodo\" title=\"Panca a muro altezza bar imbottita in tessuto trapuntato con bottoni con corrimano e dettaglio chiodo\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"color: #333333;\"><span style=\"font-size: 12pt;\"><strong>RISTORANTE CONTEMPORANEO DIVANO PANCA<\/strong><\/span><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-booths\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRSEAT0866-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Sedia ad ala con schienale alto imbottita in velluto blu navy personalizzato con struttura in legno\" title=\"Sedia ad ala con schienale alto imbottita in velluto blu navy personalizzato con struttura in legno\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">SEDIA CONTEMPORANEA CON SCHIENALE ALTO ACCENT<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/FRRSEAT0883-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Divano da smoking con struttura in metallo e rivestimento in oliva scuro\" title=\"Divano da smoking con struttura in metallo e rivestimento in oliva scuro\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">DIVANO MODERNO PER PRANZO CUCITO A MANO\u00a0 \u00a0<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/FRRSEAT0872-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Poltrona chesterfield da smoking imbottita in velluto grigio con piedini in ottone\" title=\"Poltrona chesterfield da smoking imbottita in velluto grigio con piedini in ottone\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #da8a67;\"><span style=\"color: #333333;\">POLTRONA VASCA PER PRANZO MODERNO<\/span><\/span><\/strong><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-chairs\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRSEAT0795-250x250.jpg\" width=\"250\" height=\"250\" alt=\"fabric stcitched chair for fine dining cafes\" title=\"FRRSEAT0795\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">POLTRONA DA PRANZO CONTEMPORANEA IN LEGNO<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-booths\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRSEAT0760-250x250.jpg\" width=\"250\" height=\"250\" alt=\"poltrona nera moderna in stile vittoriano per ristoranti\" title=\"sedia da pranzo del ristorante vittoriano\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">POLTRONA DA PRANZO VITTORIANA IN LEGNO INTAGLIATO<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRTABL0343-250x250.jpg\" width=\"250\" height=\"250\" alt=\"tavolo industriale moderno per ristorante us\" title=\"tavolo da pranzo industriale del ristorante\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">TAVOLO DA PRANZO COMMERCIALE MODERNO-INDUSTRIALE\u00a0 \u00a0<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRTABL0291-250x250.jpg\" width=\"250\" height=\"250\" alt=\"eleganti tavoli da pranzo in stile tornante per ristoranti\" title=\"tavolo con piano in legno e gambe a forcina\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">TAVOLO 6 POSTI IN STILE MODERNO PER PRANZO<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-chairs\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRTABL0305-250x250.jpg\" width=\"250\" height=\"250\" alt=\"tavolo da pranzo rustico moderno altezza bar\" title=\"tavolo da pranzo per ristorante moderno altezza bar\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">TAVOLO ALTEZZA BAR IN GAMBE IN GHISA<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-booths\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRSEAT0695-250x250.jpg\" width=\"250\" height=\"250\" alt=\"poltroncina in velluto per ristoranti e caff\u00e8\" title=\"sedia a pozzetto trapuntata per sala da pranzo commerciale\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">SEDIA DA PRANZO IN STILE VASCA CONTEMPORANEA<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRSEAT0724-250x250.jpg\" width=\"250\" height=\"250\" alt=\"sgabelli da bar tradizionali indiani in legno intagliato per uso ristorante\" title=\"FRRSEAT0724\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">SGABELLO RUSTICO MODERNO IN LEGNO INTAGLIATO<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/it\/c\/restaurant-tables\/attribute-style-modern\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/04\/FRRTABL0317-250x250.jpg\" width=\"250\" height=\"250\" alt=\"tavolo da ristorante moderno con piano in marmo e base placcata oro\" title=\"Tavolo da ristorante moderno con piano in marmo\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598013084851  vc_custom_1598013084851\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-size: 16px;\">SQUISITO TAVOLO PLACCATO ORO CON PIANO IN QUARZO<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"section-element vc_row-o-full-height vc_row-o-columns-middle vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h6 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">MARCHI E CLIENTI CON CUI ABBIAMO LAVORATO<\/h6><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1599360397581  vc_custom_1599360397581\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Co-Working-Space-Furniture-Client-Logo-InstaOffice.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Co Working Space Furniture Client Logo - InstaOffice\" title=\"Co Working Space Furniture Client Logo - InstaOffice\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Commercial-Furniture-Client-Logo-TCS-Tata-Consultancy-Services-Group-Worldwide.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili commerciali - Gruppo TCS (Tata Consultancy Services) in tutto il mondo\" title=\"Logo del cliente di mobili commerciali - Gruppo TCS (Tata Consultancy Services) in tutto il mondo\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Office-Furniture-Client-Logo-Microsoft-Group-Worldwide.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili per ufficio - Microsoft Group Worldwide\" title=\"Logo del cliente di mobili per ufficio - Microsoft Group Worldwide\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Vacation-Resort-Furniture-Client-Logo-Select-Hotels-Group.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente dei mobili per resort per le vacanze - Seleziona il gruppo di hotel\" title=\"Logo del cliente dei mobili per resort per le vacanze - Seleziona il gruppo di hotel\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Luxury-Hotel-Furniture-Client-Logo-Latitude-Hotel-Group-Boutique-Hotels-Chain-in-Africa.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili per hotel di lusso - Latitude Hotel Group, Africa\" title=\"Logo del cliente di mobili per hotel di lusso - Latitude Hotel Group, Africa\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Brewpub-Furniture-Client-Logo-Byg-Brewsky-Bengaluru-Asias-Largest-Brewery.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo Brewpub Furniture Client - Byg Brewsky, Bengaluru, il pi\u00f9 grande birrificio dell&#039;Asia\" title=\"Logo Brewpub Furniture Client - Byg Brewsky, Bengaluru, il pi\u00f9 grande birrificio dell&#039;Asia\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 35px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Bakery-Furniture-Client-Logo-German-Bakery-Group-Pune.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili da forno - Gruppo tedesco di prodotti da forno, Pune\" title=\"Logo del cliente di mobili da forno - Gruppo tedesco di prodotti da forno, Pune\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Coffee-Shop-Furniture-Client-Logo-Cafe-Buddys-Espresso.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili per caffetteria - Cafe Buddy&#039;s Espresso\" title=\"Logo del cliente di mobili per caffetteria - Cafe Buddy&#039;s Espresso\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Grill-Kitchen-Furniture-Client-Logo-Big-Tap-Brewhouse-Goa.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Grill Kitchen Furniture Logo del cliente - Big Tap Brewhouse Goa\" title=\"Grill Kitchen Furniture Logo del cliente - Big Tap Brewhouse Goa\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Pub-Chain-Furniture-Client-Logo-Vapour-Bar-Pan-India-Bars-Pubs-Chain.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo cliente di mobili per catene di pub - Vapor Bar, catena di bar e pub Pan India\" title=\"Logo cliente di mobili per catene di pub - Vapor Bar, catena di bar e pub Pan India\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Brewery-Furniture-Client-Logo-Ironhill-Brewery-Chain.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili per birreria - Catena di birrerie Ironhill\" title=\"Logo del cliente di mobili per birreria - Catena di birrerie Ironhill\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Bar-Chain-Furniture-Client-Logo-Tipsy-Bull-The-Bar-Exchange-India-wide-Bars-Pubs-Chain.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Logo del cliente di mobili per catene di bar - Tipsy Bull The Bar Exchange, catena di bar e pub in tutta l&#039;India\" title=\"Logo del cliente di mobili per catene di bar - Tipsy Bull The Bar Exchange, catena di bar e pub in tutta l&#039;India\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 35px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"section-element vc_row-o-full-height vc_row-o-columns-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h6 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">DISEGNI COMPLETAMENTE PERSONALIZZABILI<\/h6><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333; font-size: 12pt;\">Personalizza tutti gli aspetti della tua selezione di mobili quando acquisti con noi<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1598342877833\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Furniture-Styles-Designs-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Stili e disegni di mobili personalizzati\" title=\"Stili e disegni di mobili personalizzati\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Variety-of-Wood-Options-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Variet\u00e0 di opzioni di legno\" title=\"Variet\u00e0 di opzioni di legno\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1598342877833\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Wood-Finishes-and-Stains-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Finiture e macchie di legno personalizzate\" title=\"Finiture e macchie di legno personalizzate\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Leather-Vinyl-or-Fabric-Options-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Opzioni personalizzate in vinile o tessuto in pelle\" title=\"Opzioni personalizzate in vinile o tessuto in pelle\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"section-element vc_custom_1599866954172 vc_row-has-fill vc_row-o-content-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_col-lg-offset-1 vc_col-lg-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div style=\"text-align: justify;\">\n<h4><span style=\"color: #003366; font-size: 12pt;\">Elementi di arredo moderno per ristoranti, bar o caff\u00e8<\/span><\/h4>\n<p><span style=\"font-size: 10pt;\">I mobili del ristorante in stile moderno avvolgono funzionalit\u00e0 e minimalismo. La maggior parte dei ristoranti, bar o caffetterie con sfumature interne moderne o contemporanee sono caratterizzate da mobili che utilizzano mobili in metallo in tonalit\u00e0 vivaci e forme funzionali.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43950 size-medium\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining-300x300.jpg\" alt=\"mobili e arredi moderni per cene di ristoranti commerciali\" width=\"300\" height=\"300\" srcset=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining-300x300.jpg 300w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining-150x150.jpg 150w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining-12x12.jpg 12w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining-100x100.jpg 100w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Modern-Furniture-For-restaurant-dining.jpg 536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Con forme diritte e talvolta organiche, ci\u00f2 che manca nei dettagli ai mobili in stile moderno, pi\u00f9 che compensare la vivacit\u00e0. La maggior parte dei moderni mobili da esterno per ristoranti utilizza tavoli in vetro o marmo \/ granito insieme a sedie da esterno in legno di teak o metallo non solo per migliorare il loro ambiente, ma anche per aggiungere l&#039;elemento di durevolezza ai loro mobili.\u00a0<\/span><\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><\/section>","protected":false},"excerpt":{"rendered":"MODERN &amp; CONTEMPORARY RESTAURANT FURNITURE Home \/ Restaurant Furniture \/ Modern Restaurant Furniture Our modern restaurant furniture contrasts with our classic-themed restaurant furniture in that it usually features sharper lines, &hellip;","protected":false},"author":2,"featured_media":37281,"parent":10840,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/fullwidth-template.php","meta":{"footnotes":""},"class_list":["post-37174","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"rankMath":{"parentDomain":"furnitureroots.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":true,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"modern-style","permalinkFormat":"https:\/\/furnitureroots.com\/it\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/furnitureroots.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"Modern Restaurant Furniture: Chairs, Booths, Tables for Restaurants","description":"Get latest designs in modern restaurant furniture - chairs, booths, tables, cafe &amp; bistro sets &amp; bar counters at wholesale prices. Delivered globally.","focusKeywords":"Modern Restaurant Furniture","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":false,"max-video-preview":false,"max-image-preview":false,"a:3:{s:11:":false,"quot;max-snippet":false,"quot;;s:2:":false,"quot;-1":false,"quot;;s:17:":false,"quot;max-video-preview":false,"quot;max-image-preview":false,"quot;;s:5:":false,"quot;large":false,"quot;;}":false},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"play","facebookAuthor":"","twitterCardType":"summary_large_image","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"play","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"Dhritiman Ranawat","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":true},"homeUrl":"https:\/\/furnitureroots.com\/it\/","objectID":37174,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/furnitureroots.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/www\/furnitureroots_264\/public\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/furnitureroots.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/www\/furnitureroots_264\/public\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/11\/FurnitureRoots-Site-Icon-1.png","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Ffurnitureroots.com%2Fit%2F&r=https%3A%2F%2Ffurnitureroots.com%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F37174%3Fnonce%3D90f209574d","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/10\/FR-Linear-Logo-1-100x100.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/furnitureroots.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/pages\/37174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/comments?post=37174"}],"version-history":[{"count":22,"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/pages\/37174\/revisions"}],"predecessor-version":[{"id":44029,"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/pages\/37174\/revisions\/44029"}],"up":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/pages\/10840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/media\/37281"}],"wp:attachment":[{"href":"https:\/\/furnitureroots.com\/it\/wp-json\/wp\/v2\/media?parent=37174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}