{"id":10840,"date":"2019-12-16T11:09:09","date_gmt":"2019-12-16T11:09:09","guid":{"rendered":"http:\/\/furnitureroots.com\/?page_id=10840"},"modified":"2025-06-04T06:51:24","modified_gmt":"2025-06-04T06:51:24","slug":"restaurant-furniture","status":"publish","type":"page","link":"https:\/\/furnitureroots.com\/es\/mobiliario-restaurante\/","title":{"rendered":"Mobiliario de Restaurante"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"section-element vc_custom_1621565147419 vc_row-has-fill\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h1 style=\"font-size: 28px;color: #333333;text-align: center\" class=\"vc_custom_heading vc_custom_1626249603192\">MUEBLES DE RESTAURANTE Y BAR<\/h1>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div style=\"text-align: justify;\">\n<p><span style=\"font-size: 12pt;\">Design a restaurant with character. FurnitureRoots is a <a href=\"\/es\/restaurant-furniture\/\"><strong>fabricante de muebles para restaurantes<\/strong><\/a> supplying furniture to <strong>global restaurant chains, QSR and cafe brands<\/strong>, including tables, chairs, booths \/ banquettes, barstools, bar tables, sofas, bar &amp; service counters &amp; countertops, and outdoor restaurant furniture.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">We manufacture and export <strong data-start=\"712\" data-end=\"743\">custom restaurant furniture<\/strong> for cafes, QSRs, and dining spaces globally. If you&#8217;re also furnishing <strong data-start=\"806\" data-end=\"845\">hotel lobbies, rooms, or receptions<\/strong>, explore our full range of <a class=\"cursor-pointer\" href=\"\/es\/hotel-furniture\/\" target=\"_new\" rel=\"noopener\" data-start=\"873\" data-end=\"939\"><strong data-start=\"874\" data-end=\"893\">muebles de hotel<\/strong><\/a> y <a href=\"\/es\/contract-furniture-manufacturers\/\"><strong>contract-furniture<\/strong><\/a> tailored for <a href=\"\/es\/clients\/\">global hospitality brands<\/a>.<\/span><\/p>\n<p>As wholesale restaurant furniture manufacturer, we believe in providing heavy-duty, contract grade, custom restaurant furniture at wholesale prices. Our expertise in design, quality and manufacturer pricing has helped supply highest quality, bespoke restaurant furniture to over 30 countries globally.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f36373-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"36373\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/10840#wpcf7-f36373-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/10840#wpcf7-f36373-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"36373\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f36373-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-row dashingform\">\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre: Jon Doe\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico: Jon@gmail.com\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"country\"><option value=\"\">Seleccionar pa\u00eds<\/option><option value=\"Australia\">Australia<\/option><option value=\"Brazil\">Brasil<\/option><option value=\"Canada\">Canad\u00e1<\/option><option value=\"Chile\">Chile<\/option><option value=\"Dubai\">Dubai<\/option><option value=\"France\">Francia<\/option><option value=\"Germany\">Alemania<\/option><option value=\"India\">India<\/option><option value=\"Italy\">Italia<\/option><option value=\"Netherlands\">Pa\u00edses Bajos<\/option><option value=\"Portugal\">Portugal<\/option><option value=\"Russia\">Rusia<\/option><option value=\"Saudi Arabia\">Arabia Saudita<\/option><option value=\"South Africa\">Sud\u00e1frica<\/option><option value=\"Spain\">Espa\u00f1a<\/option><option value=\"United Kingdom\">Reino Unido<\/option><option value=\"United States\">Estados Unidos<\/option><option value=\"Other\">Otro<\/option><\/select><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"Contact\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel cf71\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono: 000 000 011\" value=\"\" type=\"tel\" name=\"Contact\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-Message\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"H\u00e1blanos de tu proyecto\" value=\"\" type=\"text\" name=\"your-Message\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">Please prove you are human by selecting the<span> car<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t<\/p>\n\t<div class=\"grid-20\">\n\t\t<p><label id=\"contact-form-click\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Obtener ayuda de expertos\" \/><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-size: 12pt;\">\u00a1Programe un horario adecuado para una llamada con nuestro experto en muebles!<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"section-element vc_custom_1598099559805 vc_row-no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">CATEGOR\u00cdAS DE PRODUCTO<\/h2><div class=\"vc_row wpb_row vc_inner vc_row-fluid rest vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/es\/restaurant-tables\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img fetchpriority=\"high\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/4-seater-restaurant-table-300x300.png\" width=\"300\" height=\"300\" alt=\"mesa de madera de mediados de siglo para restaurantes de dise\u00f1o\" title=\"Mesa de restaurante de 4 plazas\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><a href=\"\/es\/restaurant-table\/\"><span style=\"text-decoration: underline; font-size: 14pt; font-family: verdana, geneva, sans-serif;\"><strong><span style=\"text-decoration: underline;\">MESAS COMEDOR RESTAURANTE<\/span><\/strong><\/span><\/a><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Tableros y bases de mesas comerciales y de restaurantes en dise\u00f1os \u00fanicos hechos a medida en madera de ingenier\u00eda, madera maciza, metal y m\u00e1rmol.<br \/>\n<a href=\"\/es\/c\/restaurant-tables\/attribute-style-modern\/\"><span style=\"text-decoration: underline;\"><span style=\"color: #da8a67; text-decoration: underline;\">Mesas de restaurante modernas<\/span><\/span><\/a><br \/>\n<a href=\"\/es\/c\/restaurant-tables\/attribute-table-type-bar-table\/\"><span style=\"text-decoration: underline;\"><span style=\"color: #da8a67; text-decoration: underline;\">Mesas De Comedor De Bar<\/span><\/span><\/a><br \/>\n<a href=\"\/es\/c\/restaurant-tables\/attribute-table-type-bistro\/\"><span style=\"text-decoration: underline;\"><span style=\"color: #da8a67; text-decoration: underline;\">Mesas Bistro<\/span><\/span><\/a><br \/>\n<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/es\/restaurant-furniture\/restaurant-seating\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/06\/Chairs-1-300x300.jpg\" width=\"300\" height=\"300\" alt=\"silla tapizada de cuero moderno en cuero blanco\" title=\"Sillas de restaurante\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><a href=\"\/es\/restaurant-furniture\/restaurant-seating\/\"><span style=\"text-decoration: underline;\"><strong>ASIENTOS DE RESTAURANTE<\/strong><\/span><\/a><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\" class=\"translation-block\"><span style=\"font-size: 12pt\">Productos para asientos comerciales y de restaurante que brindan comodidad y atractivo incomparables a su bar, cafeter\u00eda o bistr\u00f3<br> <a href=\"\/es\/restaurant-chairs\/\" target=\"_self\"><span style=\"text-decoration: underline;color: #da8a67\">Sillas de restaurante<\/span><\/a><br> <span style=\"text-decoration: underline;color: #da8a67\"><a style=\"color: #da8a67;text-decoration: underline\" href=\"\/es\/restaurant-bar-stools\/\" target=\"_blank\" rel=\"noopener\">Taburetes de bar para restaurante<\/a><\/span><br> <a href=\"\/es\/restaurant-booths\/\" target=\"_self\"><span style=\"text-decoration: underline;color: #da8a67\">Cabinas de restaurante<\/span><\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/es\/outdoor-restaurant-furniture\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Outdoor-Furniture-1-300x300.jpg\" width=\"300\" height=\"300\" alt=\"tejido de cuerda, muebles resistentes para patios y exteriores\" title=\"Mueble para exteriores\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\" class=\"translation-block\"><span style=\"font-size: 14pt;font-family: verdana, geneva, sans-serif;color: #000000\"><a style=\"color: #000000\" href=\"\/es\/outdoor-restaurant-furniture\/\" target=\"_self\"><span style=\"text-decoration: underline\"><strong>MUEBLES DE RESTAURANTE<\/strong> AL AIRE LIBRE<\/span><\/a><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Muebles resistentes para exteriores para restaurantes en azoteas, bistr\u00f3s y caf\u00e9s en el patio y jard\u00edn que durar\u00e1n a\u00f1os.<br \/>\n<\/span><span style=\"font-size: 12pt;\"><a href=\"\/es\/c\/restaurant-tables\/attribute-table-type-bistro\/\"><span style=\"text-decoration: underline;\"><span style=\"color: #da8a67; text-decoration: underline;\">Mesas de restaurante al aire libre<\/span><\/span><\/a><br \/>\n<a href=\"\/es\/c\/restaurant-chairs\/attribute-usage-outdoor\/\"><span style=\"text-decoration: underline;\"><span style=\"color: #da8a67; text-decoration: underline;\">Sillas de restaurante al aire libre<\/span><\/span><\/a><br \/>\n<a href=\"\/es\/c\/restaurant-tables-and-chairs\/attribute-usage-outdoor\/\"><span style=\"text-decoration: underline;\"><span style=\"color: #da8a67; text-decoration: underline;\">Juegos de comedor al aire libre<\/span><\/span><\/a><br \/>\n<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"section-element vc_custom_1598099559805 vc_row-no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">M\u00c1S PRODUCTOS QUE HACEMOS Y VENDEMOS<\/h2><div class=\"vc_row wpb_row vc_inner vc_row-fluid rest vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/es\/restaurant-tables\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/long-restaurant-dining-sofa.png\" width=\"300\" height=\"300\" alt=\"sof\u00e1 grande tapizado en tela para restaurantes comerciales\" title=\"Sof\u00e1 de comedor largo para restaurante\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><a href=\"\/es\/c\/restaurant-sofas\/\"><span style=\"text-decoration: underline; font-size: 14pt; font-family: verdana, geneva, sans-serif;\"><strong><span style=\"text-decoration: underline;\">SOF\u00c1S DE RESTAURANTE<\/span><\/strong><\/span><\/a><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Sof\u00e1s para \u00e1reas de recepci\u00f3n en profundos estilos contempor\u00e1neos o vintage o grandes sof\u00e1s de estilo seccional para comedor. Posibles opciones de personalizaci\u00f3n disponibles\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/es\/restaurant-furniture\/restaurant-seating\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/bench-and-seating-set.png\" width=\"300\" height=\"300\" alt=\"mesa y banco de restaurante r\u00fastico\" title=\"Conjunto de banco y asiento\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><a href=\"\/es\/c\/restaurant-benches\/\"><span style=\"text-decoration: underline;\"><strong>BANCOS DE RESTAURANTE<\/strong><\/span><\/a><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\">Un mueble popular, resistente y rentable, los bancos son excelentes para irradiar un ambiente informal y tambi\u00e9n duran m\u00e1s. Opciones premium disponibles<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"\/es\/outdoor-restaurant-furniture\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/4-seater-dining-sets-for-restaurants-300x300.png\" width=\"300\" height=\"300\" alt=\"juegos de mesa y sillas para restaurantes peque\u00f1os y econ\u00f3micos\" title=\"Juegos de comedor de 4 plazas para restaurantes\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><a href=\"\/es\/c\/restaurant-tables-and-chairs\/\"><span style=\"text-decoration: underline;\"><strong>SILLAS DE MESA DE RESTAURANTE<\/strong><\/span><\/a><\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Ahorre costos en su pedido de muebles comprando juegos de mesa y sillas preestablecidos y evite la molestia de combinar combinaciones y altos gastos<\/span><span style=\"font-size: 12pt;\"><br \/>\n<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"section-element\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h4 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">ESTILOS DE DISE\u00d1O DE RESTAURANTES QUE HACEMOS<\/h4><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><span style=\"color: #323232;\"><strong><span style=\"font-size: 14pt; color: #da8a67;\"><span style=\"font-family: verdana, geneva, sans-serif;\">MUEBLES CONTEMPORANEOS<\/span><\/span><\/strong><\/span><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Exquisite-Modern-Restaurant-Interiors-250x250.jpg\" width=\"250\" height=\"250\" alt=\"proyecto de mobiliario y accesorios de restaurante contempor\u00e1neo de FurnitureRoots\" title=\"Exquisitos interiores de restaurantes modernos\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #da8a67; font-family: verdana, geneva, sans-serif;\"><strong>MUEBLES INDUSTRIALES<\/strong><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/Industrial-Bar-Counter-by-FurnitureRoots-for-Kattholmen-Restaurant-Sweden-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Mobiliario industrial para restaurante\" title=\"Mobiliario industrial para restaurante\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #da8a67; font-family: verdana, geneva, sans-serif;\"><strong>MUEBLES RUSTICOS<\/strong><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/Rustic-Restaurant-Furniture-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Mobiliario de restaurante r\u00fastico\" title=\"Mobiliario de restaurante r\u00fastico\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #da8a67; font-family: verdana, geneva, sans-serif;\"><strong>FINE DINING FURNITURE<\/strong><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/08\/Fine-Dining-Restaurant-Furniture-Set-Up-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Proyecto de muebles y accesorios de restaurantes comerciales de alta cocina.\" title=\"Montaje de muebles de restaurante de alta cocina\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #da8a67; font-family: verdana, geneva, sans-serif;\"><strong>MUEBLE PARA EXTERIORES<\/strong><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/03\/Outdoor-RF-250x250.jpg\" width=\"250\" height=\"250\" alt=\"mesas y sillas en el jard\u00edn del hotel\" title=\"\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif;\"><a href=\"\/es\/pub-furniture\/\"><span style=\"color: #323232; font-size: 12pt;\"><strong><span style=\"font-size: 14pt; color: #da8a67;\">MUEBLES ESTILO PUB<\/span><\/strong><\/span><\/a><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/03\/Pub-Furniture-250x250.jpg\" width=\"250\" height=\"250\" alt=\"muebles antiguos de estilo taberna\" title=\"Mobiliario Pub\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #da8a67; font-family: verdana, geneva, sans-serif;\"><a style=\"color: #da8a67;\" href=\"\/es\/cafe-furniture\/\"><strong>MUEBLES DE CAF\u00c9<\/strong><\/a><\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/03\/Cafe-Style-Interiors-250x250.jpg\" width=\"250\" height=\"250\" alt=\"dise\u00f1o de muebles de cafeter\u00eda\" title=\"Interiores Estilo Caf\u00e9\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1545297785736  vc_custom_1545297785736\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><h4 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">FURNISHING MORE THAN JUST RESTAURANTS<\/h4>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\">In addition to cafes and dining venues, we also specialize in <a href=\"\/es\/hotel-furniture\/\">muebles de hotel<\/a> \u2014 including beds, wardrobes, reception desks, and more. Explore our <a href=\"\/es\/hotel-furniture\/\">hospitality furniture range<\/a> tailored for upscale hotels and resorts worldwide.<\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"section-element vc_custom_1599841504291 vc_row-has-fill vc_row-o-full-height vc_row-o-columns-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h6 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">COMPRE MUEBLES ONLINE EN 3 SENCILLOS PASOS<\/h6><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1599360314171  vc_custom_1599360314171\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>1.<\/strong><\/span><\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center   homepage-single-icons\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Order-Process-Step-1-Discover-Custom-Furniture-Designs-on-website.svg\" class=\"vc_single_image-img attachment-medium\" alt=\"Proceso de pedido, paso 1: &#039;Descubra dise\u00f1os de muebles personalizados en el sitio web&#039;\" title=\"Proceso de pedido, paso 1: &#039;Descubra dise\u00f1os de muebles personalizados en el sitio web&#039;\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 16px; color: #000000;\">Seleccione entre m\u00e1s de 2500 dise\u00f1os de muebles en el sitio web o comparta el suyo<\/span><\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>2.<\/strong><\/span><\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center   homepage-single-icons\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Order-Process-Step-2-Discuss-Furniture-Customizations.svg\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"Proceso de pedido, paso 2: &#039;Ll\u00e1menos para discutir las personalizaciones de muebles para su negocio&#039;\" title=\"Proceso de pedido, paso 2: &#039;Ll\u00e1menos para discutir las personalizaciones de muebles para su negocio&#039;\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #000000;\">Discuta las personalizaciones en <span style=\"text-decoration: underline;\"><a style=\"color: #000000;\" href=\"mailto:business@furnitureroots.com\">business@furnitureroots.com<\/a><\/span><\/span><\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>3.<\/strong><\/span><\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center   homepage-single-icons\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/12\/Order-Process-Step-3-Order-Delivery.svg\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"Proceso de pedido: paso 3 &#039;Obtener la entrega del pedido&#039;\" title=\"Proceso de pedido: paso 3 &#039;Obtener la entrega del pedido&#039;\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 16px; color: #000000;\">Desempaqueta los muebles que combinan perfectamente con tu decoraci\u00f3n en unos d\u00edas<\/span><\/p>\n<p><code style=\"display: none;\"><br \/>\n<\/code><code style=\"display: none;\"><br \/>\n<\/code><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"section-element vc_custom_1599841112419\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h4 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">DISE\u00d1O DE MUEBLES DE RESTAURANTE: PROYECTOS<\/h4><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598151627634  vc_custom_1598151627634\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Bar-Counter-by-FurnitureRoots-for-Kattholmen-Restaurant-Sweden-2-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Barra de bar personalizada por FurnitureRoots para restaurante Kattholmen Suecia\" title=\"Barra de bar personalizada por FurnitureRoots para restaurante Kattholmen Suecia\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">KATTHOLMEN FINE-DINE<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/07\/Bespoke-Designer-Hotel-Furniture-Project-by-FurnitureRoots-Latitude-Hotels-Africa-7-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Mobiliario de restaurante en \u00c1frica: por FurnitureRoots para Latitude Hotels Africa\" title=\"Mobiliario de restaurante en \u00c1frica: por FurnitureRoots para Latitude Hotels Africa\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">HOTEL LATITUD<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Restaurant-Furniture-The-Yellow-Chillis-Restaurant-in-London-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Muebles-restaurante-personalizados-The-Yellow-Chillis-Restaurant-in-London\" title=\"Muebles de restaurante personalizados The Yellow Chillis Restaurant en Londres\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">RESTAURANTE CHILI AMARILLO<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/07\/Bespoke-Brewpub-Diner-Furniture-Project-by-FurnitureRoots-Vapour-Bar-Exchange-Gurgaon-1-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Diner Furniture: por FurnitureRoots para Vapor Bar Exchange en Gurgaon\" title=\"Diner Furniture: por FurnitureRoots para Vapor Bar Exchange en Gurgaon\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">BAR DE VAPOR Y CENA<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/07\/Bespoke-Beachside-Hospitality-Furniture-Project-by-FurnitureRoots-Gargoor-1-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Proyecto de mobiliario de hosteler\u00eda a medida junto a la playa de FurnitureRoots Gargoor 1\" title=\"Proyecto de mobiliario de hosteler\u00eda a medida junto a la playa de FurnitureRoots Gargoor 1\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">CAF\u00c9 GARGOOR<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/09\/Bespoke-Brewpub-Furniture-Project-by-FurnitureRoots-Byg-Brewski-Open-Air-Pub-Bengaluru-7-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Proyecto de muebles de cervecer\u00eda a medida por FurnitureRoots Byg Brewski Open Air Pub Bengaluru 7\" title=\"Proyecto de muebles de cervecer\u00eda a medida por FurnitureRoots Byg Brewski Open Air Pub Bengaluru 7\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">BYG BREWSKI BREWPUB<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/11\/Bespoke-Resto-Pub-Furniture-Project-by-FurnitureRoots-Leather-Resto-Pub-Armchairs-Little-Easy-Mumbai-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Proyecto de muebles de pub Resto a medida de FurnitureRoots Sillones de pub Resto de cuero Little Easy, Mumbai\" title=\"Proyecto de muebles de pub Resto a medida de FurnitureRoots Sillones de pub Resto de cuero Little Easy, Mumbai\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">POCO F\u00c1CIL RESTOBAR<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/10\/Bespoke-Micro-Brewery-Furniture-Project-by-FurnitureRoots-Iron-Hill-Micro-Brewery-Grill-Vizag-1-250x250.jpg\" width=\"250\" height=\"250\" alt=\"Brewpub Furniture: por FurnitureRoots para Iron Hill Micro Brewery &amp; Grill, Vizag 1\" title=\"Brewpub Furniture: por FurnitureRoots para Iron Hill Micro Brewery &amp; Grill, Vizag 1\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Microcervecer\u00eda IRONHILL<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_btn3-container vc_btn3-center\" ><a onmouseleave=\"this.style.borderColor='#da8a67'; this.style.backgroundColor='transparent'; this.style.color='#da8a67'\" onmouseenter=\"this.style.borderColor='#da8a67'; this.style.backgroundColor='#da8a67'; this.style.color='#ffffff';\" style=\"border-color:#da8a67; color:#da8a67;\" class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-rounded vc_btn3-style-outline-custom\" href=\"#schedule-a-call\" title=\"\">Programe una llamada gratuita<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_btn3-container vc_btn3-center\" ><a onmouseleave=\"this.style.borderColor='#da8a67'; this.style.backgroundColor='transparent'; this.style.color='#da8a67'\" onmouseenter=\"this.style.borderColor='#da8a67'; this.style.backgroundColor='#da8a67'; this.style.color='#ffffff';\" style=\"border-color:#da8a67; color:#da8a67;\" class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-rounded vc_btn3-style-outline-custom\" href=\"\/es\/projects\/\" title=\"\" target=\"_blank\">VER TODOS LOS PROYECTOS<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"section-element vc_custom_1598099559805 vc_row-no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<a href=\"https:\/\/furnitureroots.com\/es\/contact-us\/\">\n<div class=\"row row-12\">\n<img decoding=\"async\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/09\/Commercial-Grade-1.png\" style=\"width:100%;\">\n<\/div>\n<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"section-element vc_custom_1599841162458 vc_row-o-full-height vc_row-o-columns-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h6 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">PERSONALIZACIONES QUE OFRECEMOS<\/h6><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #333333; font-size: 12pt;\">Personalice todos los aspectos de su selecci\u00f3n de muebles cuando compre con nosotros<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1598342877833\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Furniture-Styles-Designs-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Estilos y dise\u00f1os de muebles personalizados\" title=\"Estilos y dise\u00f1os de muebles personalizados\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Variety-of-Wood-Options-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Variedad de opciones de madera\" title=\"Variedad de opciones de madera\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1598342877833\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Wood-Finishes-and-Stains-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Acabados y tintes personalizados para madera\" title=\"Acabados y tintes personalizados para madera\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/08\/Custom-Leather-Vinyl-or-Fabric-Options-300x300.jpg\" width=\"300\" height=\"300\" alt=\"Opciones de tela o vinilo de cuero personalizadas\" title=\"Opciones de tela o vinilo de cuero personalizadas\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"section-element vc_custom_1599372438110 vc_row-has-fill vc_row-o-content-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_btn3-container vc_btn3-center vc_custom_1599723383710\" ><a onmouseleave=\"this.style.borderColor='#da8a67'; this.style.backgroundColor='transparent'; this.style.color='#da8a67'\" onmouseenter=\"this.style.borderColor='#da8a67'; this.style.backgroundColor='#da8a67'; this.style.color='#ffffff';\" style=\"border-color:#da8a67; color:#da8a67;\" class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-rounded vc_btn3-style-outline-custom\" href=\"#schedule-a-call\" title=\"\">OBTENGA MUEBLES A PRECIOS DIRECTOS DE FABRICANTE!<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div id=\"testimonial-row\" class=\"section-element vc_custom_1599841132521 vc_row-o-content-middle vc_row-flex\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h4 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\"><a href=\"\/es\/testimonials\/\">TESTIMONIOS DE CLIENTES<\/a><\/h4><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"section-element vc_custom_1599549538329 vc_row-has-fill\"><div class=\"container\"><div class=\"row\"><div class=\"down-form wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 75px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f36373-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"36373\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/10840#wpcf7-f36373-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/10840#wpcf7-f36373-o2\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"36373\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f36373-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-row dashingform\">\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre: Jon Doe\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico: Jon@gmail.com\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"country\"><option value=\"\">Seleccionar pa\u00eds<\/option><option value=\"Australia\">Australia<\/option><option value=\"Brazil\">Brasil<\/option><option value=\"Canada\">Canad\u00e1<\/option><option value=\"Chile\">Chile<\/option><option value=\"Dubai\">Dubai<\/option><option value=\"France\">Francia<\/option><option value=\"Germany\">Alemania<\/option><option value=\"India\">India<\/option><option value=\"Italy\">Italia<\/option><option value=\"Netherlands\">Pa\u00edses Bajos<\/option><option value=\"Portugal\">Portugal<\/option><option value=\"Russia\">Rusia<\/option><option value=\"Saudi Arabia\">Arabia Saudita<\/option><option value=\"South Africa\">Sud\u00e1frica<\/option><option value=\"Spain\">Espa\u00f1a<\/option><option value=\"United Kingdom\">Reino Unido<\/option><option value=\"United States\">Estados Unidos<\/option><option value=\"Other\">Otro<\/option><\/select><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"Contact\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel cf71\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono: 000 000 011\" value=\"\" type=\"tel\" name=\"Contact\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"grid-20\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-Message\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"H\u00e1blanos de tu proyecto\" value=\"\" type=\"text\" name=\"your-Message\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">Please prove you are human by selecting the<span> plane<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M377 375l-83-87h34c21 0 32-25 17-40l-82-88h33c21 0 32-25 18-40L210 8c-10-11-26-11-36 0L70 120c-14 15-3 40 18 40h33l-82 88c-15 15-4 40 17 40h34L7 375c-15 16-4 41 17 41h120c0 33-11 49-34 68-12 9-5 28 10 28h144c15 0 22-19 10-28-20-16-34-32-34-68h120c21 0 32-25 17-41z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M472 200H360L256 6a12 12 0 00-10-6h-58c-8 0-14 7-12 15l34 185H100l-35-58a12 12 0 00-10-6H12c-8 0-13 7-12 14l21 106L0 362c-1 7 4 14 12 14h43c4 0 8-2 10-6l35-58h110l-34 185c-2 8 4 15 12 15h58a12 12 0 0010-6l104-194h112c57 0 104-25 104-56s-47-56-104-56z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t<\/p>\n\t<div class=\"grid-20\">\n\t\t<p><label id=\"contact-form-click\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Obtener ayuda de expertos\" \/><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-size: 10pt;\">Nuestros consultores de log\u00edstica y dise\u00f1o est\u00e1n disponibles 24 \u00d7 7 para su asistencia. \u00a1Programe una consulta gratuita hoy!<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 75px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"section-element\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h6 style=\"font-size: 24px;text-align: center\" class=\"vc_custom_heading\">CERTIFICACIONES<\/h6><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1598248942381  vc_custom_1598248942381\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"147\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/11\/FurnitureRoots-ISO-9001-2015-Certified-Company.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"FurnitureRoots Empresa certificada ISO 9001 2015\" title=\"\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\"><a href=\"https:\/\/www.iso.org\/iso-9001-quality-management.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">ISO 9001: 2015<\/a><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Certificado para la provisi\u00f3n de procesos y sistemas de producci\u00f3n de muebles de referencia internacional<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-ISO-14001-2015-Certified-Company-150x150.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"FurnitureRoots Certificado ISO 14001 2015\" title=\"FurnitureRoots Certificado ISO 14001 2015\" srcset=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-ISO-14001-2015-Certified-Company-150x150.png 150w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-ISO-14001-2015-Certified-Company-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\"><a href=\"https:\/\/www.iso.org\/standard\/60857.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">ISO 14001: 2015<\/a><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Certificado para la instalaci\u00f3n de Sistemas de Gesti\u00f3n Ambiental (EMS) para la fabricaci\u00f3n y procesamiento de muebles<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-OHSAS-18001-2007-Certified-Company-150x150.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"FurnitureRoots Empresa certificada OHSAS 18001-2007\" title=\"FurnitureRoots Empresa certificada OHSAS 18001-2007\" srcset=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-OHSAS-18001-2007-Certified-Company-150x150.png 150w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-OHSAS-18001-2007-Certified-Company-100x100.png 100w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-OHSAS-18001-2007-Certified-Company.png 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\"><a href=\"https:\/\/www.bsigroup.com\/en-US\/OHSAS-18001-Occupational-Health-and-Safety\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">BS OHSAS 18001: 2007<\/a><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Certificado para la provisi\u00f3n de est\u00e1ndares apropiados de salud y seguridad ocupacional para todos los empleados<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-European-Union-Registered-Exporter-REX-Certified-Company-150x150.jpg\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"FurnitureRoots Empresa certificada como exportador registrado en la Uni\u00f3n Europea (REX)\" title=\"FurnitureRoots Empresa certificada como exportador registrado en la Uni\u00f3n Europea (REX)\" srcset=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-European-Union-Registered-Exporter-REX-Certified-Company-150x150.jpg 150w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-European-Union-Registered-Exporter-REX-Certified-Company-100x100.jpg 100w, https:\/\/furnitureroots.com\/wp-content\/uploads\/2019\/05\/FurnitureRoots-European-Union-Registered-Exporter-REX-Certified-Company.jpg 201w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_20 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.exportcompliance.eu\/index.php\/en\/eu-export-compliance-framework\/eu-certification-eu-c-eco\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"font-size: 12pt;\">REX UE<\/span><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Registrado formalmente para exportar a la UE y un historial demostrado de cumplimiento con las regulaciones de importaci\u00f3n de la UE<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"section-element vc_custom_1545099769639 vc_row-has-fill\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #003366;\"><strong>MUEBLES DE RESTAURANTE: UNA GU\u00cdA R\u00c1PIDA<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Los muebles para restaurantes se componen principalmente de asientos y mesas. Los asientos incluyen sillas de restaurante, taburetes de bar, cabinas y banquetas y, ocasionalmente, sillas decorativas, sof\u00e1s y bancos. Las mesas comerciales consisten en mesas de comedor, mesas de altura de barra o de mostrador, mesas de bistr\u00f3 y, a veces, mostrador de bar y mostradores de recepci\u00f3n. Las mesas se componen de tapas y bases que se pueden pedir juntas o por separado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Adem\u00e1s de los muebles de interior normales, tambi\u00e9n ofrecemos muebles de exterior para el patio, el jard\u00edn o la azotea.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #969696;\"><span style=\"color: #333333;\">As a leading contract <a class=\"\" href=\"https:\/\/furnitureroots.com\/es\/indian-furniture-manufacturers\/\" target=\"_new\" rel=\"noopener\" data-start=\"1536\" data-end=\"1638\">restaurant furniture manufacturers from India<\/a>, we supply furniture for some of the named restaurants chains and brands across the globe.<\/span><\/span><\/p>\n<p>Entonces, si est\u00e1 buscando amueblar su restaurante o cenar en una decoraci\u00f3n moderna o r\u00fastica o industrial o boho, FurnitureRoots tiene la combinaci\u00f3n perfecta de dise\u00f1os a medida a precios de mayorista para su restaurante. Puede encontrar nuestra publicaci\u00f3n en <span style=\"color: #da8a67;\"><a style=\"color: #da8a67;\" href=\"\/es\/restaurant-interior-design\/\">dise\u00f1o de interiores de restaurante<\/a><\/span> useful. We&#8217;ve worked on furniture projects for restaurants that have helped them achieve tremendous cost advantage &amp; source of better quality furniture.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #003366;\"><strong>MUEBLES DE RESTAURANTE AL POR MAYOR - MESAS, SILLAS, JUEGOS DE COMEDOR Y M\u00c1S\u00a0<\/strong><\/span><\/h4>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>Asientos de restaurante<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">FurnitureRoots fabrica muebles para asientos de calidad comercial. Elija entre las siguientes opciones de asientos comerciales c\u00f3modos y elegantes: sillas de restaurante, taburetes de bar, sillas de bistr\u00f3, sillas decorativas, sof\u00e1s, cabinas y asientos de banquete, bancos, sillas de banquete, otomanas y pufs, y muebles de exterior, que est\u00e1n hechos a medida para el necesidades de un bullicioso negocio de servicios de alimentos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Estos arreglos de asientos se pueden personalizar para sus requisitos exactos. Elija entre tapicer\u00eda de cuero o tela o vinilo \/ cuero sint\u00e9tico; o seleccione entre una amplia gama de acabados y colores; o especificar dimensiones para encajar en el dise\u00f1o de manera adecuada; o decida entre muebles r\u00fasticos, industriales o modernos para adaptarse a su tema.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>Mesas de restaurante<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Encuentra la mejor combinaci\u00f3n de tableros y bases para la mesa de tu restaurante. FurnitureRoots fabrica mesas de restaurante, mesas de altura de barra y de mostrador, mesas de banquete, mesas de bistr\u00f3, mesas de caf\u00e9, mesa de vest\u00edbulo y consola, barra de bar y mostradores de recepci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Con FurnitureRoots, tiene la posibilidad de personalizar las superficies de las mesas para dise\u00f1os, materiales, dimensiones, acabados e incluso agregar algunas caracter\u00edsticas interesantes. Tambi\u00e9n puede seleccionar la forma y los dise\u00f1os de las bases de las mesas, ya sean mesas de restaurante con base de caballete, base cruzada, base de pat\u00edn o redonda \/ rectangular \/ cuadrada.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Posteriormente, elija entre tableros de madera, metal, m\u00e1rmol, granito, piedra reconstituida o vidrio para las mesas. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Luego, decida la altura de la mesa que desea: mesa de comedor est\u00e1ndar, altura de barra o mesa de altura de mostrador. Tambi\u00e9n puede agregar algunas caracter\u00edsticas ingeniosas a sus mesas: reposapi\u00e9s con placas de protecci\u00f3n, acabados protectores, agujeros para sombrillas, tapas abatibles o pernos, etc.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><a href=\"\/es\/restaurant-tables-and-chairs\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #da8a67;\"><strong>Juegos de mesa y silla de restaurante<\/strong><\/span><\/a><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #333333; font-size: 12pt;\">Olv\u00eddese de la molestia de elegir una silla y una mesa por separado y, en su lugar, seleccione entre nuestras combinaciones preseleccionadas de juegos de sillas de mesa de restaurante al por mayor, juegos de altura de barra o de mostrador, juegos de bistr\u00f3, juegos de mesa y banco y cabinas de restaurante. Simplemente navegue por nuestra selecci\u00f3n de juegos de mesa de comedor y estar\u00e1 listo para comenzar.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>Iluminaci\u00f3n de restaurante<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Cree el ambiente adecuado para sus invitados con la gama de l\u00e1mparas colgantes y l\u00e1mparas de pie de FurnitureRoots. Desde luces brillantes para su cocina, \u00e1reas de cocina hasta iluminaci\u00f3n ambiental con luces colgantes o luces de filamento expuesto o de cuerda para su cena fina hasta iluminaci\u00f3n de riel empotrada para el \u00e1rea de su bar, FurnitureRoots ofrece dise\u00f1os de iluminaci\u00f3n personalizados para sincronizar perfectamente con los interiores y decoraci\u00f3n de su restaurante.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>Restaurante muebles de exterior<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Elegir muebles para sus asientos al aire libre y la configuraci\u00f3n puede ser un poco complicado. Por un lado, casi todos los muebles de exterior deben ser m\u00e1s duraderos y robustos, manteniendo intacta la est\u00e9tica. Para las configuraciones en la azotea, normalmente recomendamos el estilo r\u00fastico o industrial, pero para los asientos al aire libre en el pavimento o frente al r\u00edo, recomendamos utilizar nuestras colecciones de muebles costeros.<\/span><\/p>\n<h5><span style=\"font-size: 12pt; color: #da8a67;\">Restaurante y bar del hotel<\/span><\/h5>\n<p style=\"text-align: justify;\" class=\"translation-block\"><span style=\"font-size: 12pt\">Hemos trabajado duro para lograr importantes puntos fuertes en los muebles de hosteler\u00eda, que son famosos por su dificultad, ya que tienen que ser de calidad comercial y tambi\u00e9n tienen que verse con dise\u00f1os impresionantes. Ahora, gracias a los diversos proyectos de <a href=\"\/es\/hotel-furniture\/\" target=\"_self\"><span style=\"color: #da8a67\">necesidades de mobiliario de hosteler\u00eda<\/span><\/a> que hemos llevado a cabo, puedes estar seguro de que proporcionamos muebles de comedor de alta calidad a un coste asequible.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">Tambi\u00e9n tenemos una variedad de dise\u00f1os de muebles para el lobby y la recepci\u00f3n de su hotel.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>Restaurante Bar y muebles de exhibici\u00f3n<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\" class=\"translation-block\"><span style=\"font-size: 10pt;color: #969696\"><span style=\"color: #333333\"><span style=\"font-size: 12pt\">FurnitureRoots tambi\u00e9n ofrece productos de muebles personalizados como <a href=\"\/es\/c\/restaurant-bar-counter\/\" target=\"_self\">mostradores de bar de restaurante de madera<\/a> , vitrinas, gabinetes de bar, carros, muebles de autom\u00f3vil y detalles de muebles para darle a su negocio una individualidad y un encanto poco comunes.<\/span><br><\/span><\/span><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #003366;\"><strong>DISE\u00d1OS DE MUEBLES DE RESTAURANTE - DISE\u00d1OS DE MESAS Y SILLAS<\/strong><\/span><\/h4>\n<div>\n<h5><span style=\"font-size: 12pt; color: #da8a67;\">MUEBLES DE RESTAURANTE MODERNO<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Los muebles de estilo moderno o contempor\u00e1neo generalmente presentan l\u00edneas m\u00e1s n\u00edtidas y una funcionalidad elegante que genera familiaridad en el ojo de los clientes. Con su paleta de colores de blanco, gris y pasteles, el mobiliario de restaurante moderno armoniza lo informal con lo informal, la masculinidad con la feminidad y, por lo tanto, atrae a una amplia gama de clientes que se acercan a su negocio de servicios de alimentos. Con una amplia gama de acabados, tama\u00f1os y estilos que ofrecemos, puede personalizar las opciones para dise\u00f1ar muebles de restaurante seg\u00fan sus preferencias y gustos exactos.\u00a0<\/span><\/p>\n<h5><span style=\"color: #da8a67; font-size: 12pt;\">MUEBLES R\u00daSTICOS DE RESTAURANTE<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Como fabricante y proveedor de muebles r\u00fasticos para restaurantes, utilizamos madera recuperada y reutilizada en un producto nuevo y funcional. Este estilo de muebles no solo ayuda a marcar la diferencia al reducir la demanda de madera reci\u00e9n cosechada, sino que tambi\u00e9n crea productos m\u00e1s fuertes que se benefician de la estabilidad caracter\u00edstica de la madera vieja. Los productos de muebles r\u00fasticos est\u00e1n completamente hechos a mano y son verdaderamente \u00fanicos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Para muebles especiales, tambi\u00e9n puede inspirarse en nuestras colecciones de muebles con incrustaciones de hueso al por mayor fabricados a medida, formas ic\u00f3nicas que son elegantemente resistentes, muebles de estilo r\u00fastico con su rico color est\u00e9tico, p\u00e1tina y el car\u00e1cter natural de la madera que brindan una antig\u00fcedad \u00fanica a la hospitalidad moderna. ajustes<\/span><\/p>\n<h5><span style=\"color: #da8a67; font-size: 12pt;\">MUEBLES DE RESTAURANTE INDUSTRIAL<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Con la creciente popularidad de los muebles de estilo industrial, un n\u00famero cada vez mayor de restaurantes est\u00e1 adoptando el dise\u00f1o industrial en su decoraci\u00f3n. Los muebles de estilo industrial infunden la fuerza del metal soldado con la calidez natural y la belleza de la madera. Suministramos muebles industriales al por mayor creados por artesanos galardonados a restaurantes de todo el mundo.<\/span><\/p>\n<h5><span style=\"font-size: 12pt; color: #da8a67;\"><strong>MUEBLES DE CUERO PARA RESTAURANTES<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Una categor\u00eda de productos b\u00e1sicos para restaurantes de alta gama, nuestros muebles de cuero para restaurantes est\u00e1n tapizados por artesanos galardonados que se enorgullecen de los productos que crean. Utilizamos cuero aut\u00e9ntico de primera calidad que no se desvanece durante d\u00e9cadas y que garantiza el m\u00e1ximo confort y al mismo tiempo repele el calor.<\/span><\/p>\n<h5><span style=\"font-size: 12pt; color: #da8a67;\">MUEBLES A MEDIDA PARA RESTAURANTES<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u00bfQuiere que su restaurante refleje su propio gusto caracter\u00edstico? Nos especializamos en la elaboraci\u00f3n de mesas personalizadas para restaurantes y hosteler\u00eda. La mayor\u00eda de nuestros muebles se pueden personalizar seg\u00fan sus especificaciones exactas.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Una vez que haya elegido el dise\u00f1o deseado, simplemente elija el marco y el material superior, la espuma y las opciones de tapizado, seleccione el acabado y cree sus propios muebles de restaurante a medida.<\/span><br \/>\n<span style=\"font-size: 12pt;\">\u00a0<\/span><br \/>\n<span style=\"font-size: 12pt;\"><span style=\"font-size: 12pt;\">Para elegir su estilo de decoraci\u00f3n, debe comprender bien a su p\u00fablico objetivo y sus gustos. Hemos trabajado con restaurantes que simplemente han sido conscientes de esto y han comprado nuestra colecci\u00f3n de muebles recuperados al por mayor para atraer a sus clientes ecoentusiastas, solo para ver un aumento de 2 veces en su negocio.<br \/>\n<\/span><\/span><span style=\"font-size: 12pt;\"><span style=\"font-size: 12pt;\">\u00a0<\/span><\/span><\/p>\n<h4 style=\"text-align: justify;\"><a href=\"\/es\/contract-furniture-manufacturers\/\"><strong><span style=\"font-size: 12pt; color: #003366;\"><span style=\"color: #da8a67;\"><span style=\"color: #003366;\">MUEBLES DE RESTAURANTE POR CONTRATO<\/span><\/span><\/span><\/strong><\/a><\/h4>\n<p><span style=\"color: #333333; font-size: 12pt;\">Cuando contratamos fabricamos muebles para restaurantes, hoteles, caf\u00e9s y tambi\u00e9n exportamos nuestros muebles a mayoristas y minoristas de todo el mundo. Esto es lo que puede esperar de nuestro servicio:\u00a0\u00a0<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>1. Dise\u00f1os a medida y totalmente personalizables<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">\u00a1Con FurnitureRoots, puede personalizar los dise\u00f1os, dimensiones, materiales, colores, acabados e ingenier\u00eda \/ hardware de cualquier producto y obtener productos de muebles que se sincronizan perfectamente con su decoraci\u00f3n!<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>2. Mobiliario de alta calidad para entornos de operaci\u00f3n hostiles<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Los restaurantes requieren muebles de calidad comercial que puedan soportar largas horas de uso, derrames de alimentos y bebidas y limpieza regular.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Como fabricante especializado de muebles para hosteler\u00eda, fabricamos muebles que se comparan con est\u00e1ndares significativamente m\u00e1s altos de durabilidad y calidad. Con nuestros productos fabricados con materias primas de grado comercial, hardware y t\u00e9cnicas y tecnolog\u00eda de carpinter\u00eda, nos aseguramos de que obtenga muebles que le duren toda la vida.<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>3. Precios directos del fabricante<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #969696;\"><span style=\"color: #333333;\">Dado que obtiene muebles directamente de un fabricante, eliminando los m\u00e1rgenes de distribuidores \/ mayoristas \/ cadena de suministro, obtiene los precios m\u00e1s bajos posibles para muebles de calidad comercial. Tenemos una s\u00f3lida experiencia en el suministro a empresas ubicadas en todos los continentes como exportadores de muebles.<\/span><br \/>\n<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>4. Fiabilidad<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">FurnitureRoots es un fabricante y exportador de muebles a medida con certificaci\u00f3n ISO 9001: 2015 con experiencia en m\u00e1s de 300 proyectos hoteleros.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #969696;\"><span style=\"color: #333333;\">Nos especializamos en la fabricaci\u00f3n de muebles de calidad comercial que est\u00e1n especialmente dise\u00f1ados para brindar robustez y durabilidad. Para que no se equivoque al comprar muebles para su negocio.<\/span><br \/>\n<\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #da8a67;\"><strong>5. Proveedor de muebles l\u00edder en el pa\u00eds<br \/>\n<\/strong><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #333333;\">Un proveedor y mayorista de muebles para restaurantes con certificaci\u00f3n ISO-9001, FurnitureRoots ofrece dise\u00f1os, suministros, productos y servicios de muebles para restaurantes a dise\u00f1adores de interiores y arquitectos, FF&amp;E \/ adquisiciones \/ abastecimiento \/ empresas de muebles por contrato sobre los requisitos de muebles de sus proyectos. Cont\u00e1ctenos si desea asociarse con FurnitureRoots como su fabricante preferido.<br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; color: #969696;\"><span style=\"color: #333333;\"><span style=\"font-size: 12pt;\">FurnitureRoots exporta y suministra muebles de restaurante en estos <a style=\"color: #333333;\" href=\"\/es\/delivery-locations\/\"><span style=\"color: #da8a67;\">Ubicaciones<\/span><\/a> a nivel mundial.<\/span><br \/>\n<\/span>\u00a0<\/span><\/p>\n<div style=\"text-align: justify;\">\n<p><span style=\"font-size: 10pt; color: #969696;\"><br \/>\n<strong><span style=\"color: #003366; font-size: 12pt;\">PREGUNTAS FRECUENTES:<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong><span style=\"color: #da8a67;\">P. \u00bfCu\u00e1nto cuestan los muebles de restaurante?<br \/>\n<\/span><\/strong><span style=\"color: #333333;\">R. Suponiendo un espacio de comedor de 2000 pies cuadrados con 25 mesas, 10 cabinas, 75 sillas y 15 taburetes, a continuaci\u00f3n se muestran los precios aproximados que puede estar pagando por los muebles del restaurante:<br \/>\n<\/span><\/span><\/p>\n<table style=\"border-collapse: collapse; width: 100%; height: 168px;\">\n<tbody>\n<tr style=\"height: 28px;\">\n<td style=\"width: 30.454545454545457%; text-align: center; height: 28px;\"><\/td>\n<td style=\"width: 23.939393939393934%; text-align: center; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>ECONOM\u00cdA<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393945%; text-align: center; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>RANGO MEDIO<\/strong><\/span><\/td>\n<td style=\"width: 21.666666666666664%; text-align: center; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>FINE-DINE<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 30.454545454545457%; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>Precio de la silla de restaurante (en USD)<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393934%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">1,750<\/span><\/td>\n<td style=\"width: 23.939393939393945%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">3,250<\/span><\/td>\n<td style=\"width: 21.666666666666664%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">5,000<\/span><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 30.454545454545457%; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>Precio de la mesa del restaurante (en USD)<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393934%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">2,000<\/span><\/td>\n<td style=\"width: 23.939393939393945%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">3,000<\/span><\/td>\n<td style=\"width: 21.666666666666664%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">4,000<\/span><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 30.454545454545457%; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>Precio del taburete de bar del restaurante (en USD)<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393934%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">400<\/span><\/td>\n<td style=\"width: 23.939393939393945%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">700<\/span><\/td>\n<td style=\"width: 21.666666666666664%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">1,000<\/span><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 30.454545454545457%; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>Precio del puesto de restaurante (en USD)<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393934%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">1,450<\/span><\/td>\n<td style=\"width: 23.939393939393945%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">2,000<\/span><\/td>\n<td style=\"width: 21.666666666666664%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\">2,650<\/span><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 30.454545454545457%; height: 28px;\"><span style=\"color: #333333; font-size: 12pt;\"><strong>Precio de muebles de restaurante (en USD)<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393934%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\"><strong>5,600<\/strong><\/span><\/td>\n<td style=\"width: 23.939393939393945%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\"><strong>8,950<\/strong><\/span><\/td>\n<td style=\"width: 21.666666666666664%; height: 28px; text-align: center;\"><span style=\"font-size: 12pt; color: #333333;\"><strong>12,650<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-size: 12pt;\"><span style=\"color: #969696;\"><span style=\"color: #333333;\">Si bien estos son costos indicativos para muebles de restaurante basados en solo algunas de las opciones de muebles disponibles con nosotros. En FurnitureRoots vendemos directamente a restaurantes y mantenemos los costos bajos eliminando <span style=\"caret-color: #969696;\">m\u00faltiple<\/span> capas de distribuidores \/ mayoristas \/ proveedores, consiguiendo as\u00ed muebles que ser\u00e1n de 2 a 4 veces m\u00e1s baratos en comparaci\u00f3n con las alternativas disponibles.<\/span><br \/>\n<\/span><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\"><br \/>\n<span style=\"color: #969696;\"><strong><span style=\"color: #da8a67;\">P. \u00bfCu\u00e1ntas sillas y mesas caben en el dise\u00f1o de mi restaurante?<\/span><br \/>\n<\/strong><\/span><\/span><\/strong><span style=\"color: #da8a67;\"><span style=\"color: #333333;\">A. Proporcione entre 12 y 18 pies cuadrados por cliente. Por lo tanto, un restaurante tiene capacidad para 100-150 comensales en 2000 pies cuadrados de \u00e1rea de comedor dedicada, excluyendo el \u00e1rea de cocina. Esto incluye un \u00e1rea de paso de 18 pulgadas entre las mesas para facilitar el movimiento, pero excluye los pasillos m\u00e1s anchos que quiz\u00e1s desee crear para acomodar a los clientes en silla de ruedas.<\/span><\/span><span style=\"color: #da8a67;\"><br \/>\n<\/span><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\"><br \/>\nP. \u00bfPueden ayudarme a dise\u00f1ar los muebles de mi restaurante?<br \/>\n<\/span><\/strong><span style=\"color: #333333;\">R. S\u00ed, podemos. Lo ayudaremos en todo el proceso, desde la identificaci\u00f3n de los mejores dise\u00f1os, dimensiones, materiales y acabados de muebles de restaurante, hasta la elaboraci\u00f3n del embalaje, la log\u00edstica y el soporte posventa. Preg\u00fantele a cualquiera de nuestros clientes existentes y estar\u00e1 seguro de recibir comentarios positivos sobre nuestros servicios.<\/span><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\">P. \u00bfFabrican muebles desde cero?<br \/>\n<\/span><\/strong><span style=\"color: #333333;\">R. S\u00ed, lo hacemos, aunque tambi\u00e9n tenemos varias colecciones listas para usar. Sin embargo, dado que nuestras personalizaciones cuestan muy poco, la mayor\u00eda de nuestros clientes las personalizan; es entonces cuando las fabricamos desde cero.<\/span><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\">P. \u00bfQu\u00e9 materiales usas para los muebles?\u00a0<\/span><\/strong><\/span><br \/>\n<span style=\"color: #333333; font-size: 12pt;\">R. Dependiendo de las preferencias de nuestros clientes y de los muebles en s\u00ed, utilizamos tapizados de madera, metal, cuero \/ terciopelo \/ vinilo \/ tela y otros materiales seg\u00fan las especificaciones de dise\u00f1o del restaurante.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\">P. \u00bfCu\u00e1l es la vida \u00fatil de los muebles de restaurante?\u00a0<\/span><\/strong><\/span><br \/>\n<span style=\"color: #333333; font-size: 12pt;\">R. Dependiendo de la calidad, los muebles de restaurante pueden durar entre 2 y 20 a\u00f1os. Dos aspectos clave que afectan la vida \u00fatil de los muebles son la calidad de construcci\u00f3n y las materias primas. Las t\u00e9cnicas de carpinter\u00eda de grado contractual y los materiales de grado comercial ayudar\u00e1n a duplicar (o m\u00e1s) la vida \u00fatil de sus muebles y evitarlo de renovaciones muy costosas cada pocos a\u00f1os. \u00a0\u00a0<\/span><\/p>\n<p><span style=\"color: #da8a67; font-size: 12pt;\"><strong>P. \u00bfCu\u00e1les son los tipos de muebles espec\u00edficos que suministra adem\u00e1s de mesas, sillas y sof\u00e1s?<\/strong><\/span><br \/>\n<span style=\"color: #333333; font-size: 12pt;\">R. Adem\u00e1s de mesas, sillas y sof\u00e1s para restaurantes, ofrecemos complejas piezas de mobiliario que se utilizan principalmente en restaurantes de mediana y gran escala. Esto incluye asientos en cabinas de restaurante, mostradores de bar grandes, mesas altas, sillas y sof\u00e1s con respaldo alto, mesas de manivela ajustables en altura, vitrinas de bar o vino, y casi cualquier otro tipo de mobiliario utilizado en un restaurante. Tambi\u00e9n realizamos iluminaci\u00f3n para el restaurante, si a\u00fan no lo tienes previsto.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\">P. \u00bfA qu\u00e9 pa\u00edses realiza env\u00edos?<\/span><\/strong><\/span><br \/>\n<span style=\"color: #333333; font-size: 12pt;\">R. Entregamos en todo el mundo.<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong style=\"color: #969696;\"><span style=\"color: #da8a67;\">P. \u00bfExiste alg\u00fan requisito de cantidad m\u00ednima de pedido (MOQ)?<br \/>\n<\/span><\/strong><span style=\"color: #333333;\">R. S\u00ed, hay una cantidad m\u00ednima de pedido o un valor m\u00ednimo de pedido dado que somos un fabricante de muebles para restaurantes personalizados. P\u00f3ngase en contacto con nosotros para discutir los detalles de sus requisitos. <\/span><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong><span style=\"color: #da8a67;\">P. \u00bfUsted\u00a0<span style=\"caret-color: #da8a67;\">proporcionar personalizaciones? Cu\u00e1nto cuestan<\/span>?<\/span><br \/>\n<\/strong><span style=\"color: #333333;\">R. S\u00ed, como empresa de muebles para restaurantes a medida, ofrecemos personalizaciones. Si bien el costo de los muebles personalizados para restaurantes depende de las especificaciones, sin embargo, las personalizaciones ayudan a que los muebles se mezclen y mejoren el dise\u00f1o interior del restaurante y le den individualidad y car\u00e1cter a un restaurante, bar o cafeter\u00eda.<\/span><\/span><\/p>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"section-element\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h4 style=\"font-size: 24px;color: #000000;text-align: center\" class=\"vc_custom_heading\">RECURSOS \u00daTILES<\/h4><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text vc_custom_1621646991423  vc_custom_1621646991423\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#da8a67;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_border_circle  vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/03\/Solid-Wood-Restaurant-300x300.jpg\" width=\"300\" height=\"300\" alt=\"iluminaci\u00f3n tenue en el restaurante con muebles de madera\" title=\"Restaurante de madera maciza\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #da8a67;\"><a style=\"color: #da8a67;\" href=\"\/es\/restaurant-interior-designs\/\"><strong>DISE\u00d1OS DE INTERIORES PARA RESTAURANTES<\/strong><\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_border_circle  vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/03\/Pub-Furniture-300x300.jpg\" width=\"300\" height=\"300\" alt=\"muebles antiguos de estilo taberna\" title=\"Mobiliario Pub\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #da8a67;\"><a style=\"color: #da8a67;\" href=\"\/price-list-restaurant-furniture\/\"><strong>PRECIOS DE MUEBLES DE RESTAURANTE<\/strong><\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_border_circle  vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/furnitureroots.com\/wp-content\/uploads\/2021\/05\/Multiple-Options-300x300.jpg\" width=\"300\" height=\"300\" alt=\"diferentes opciones de mobiliario para la distribuci\u00f3n de los asientos del restaurante\" title=\"opciones de asientos\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #da8a67;\"><a style=\"color: #da8a67;\" href=\"\/restaurant-seating-plan\/\"><strong>DISE\u00d1O DE ASIENTOS PARA RESTAURANTES<\/strong><\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"RESTAURANT &amp; BAR FURNITURE Design a restaurant with character. FurnitureRoots is a restaurant furniture manufacturer supplying furniture to global restaurant chains, QSR and cafe brands, including tables, chairs, booths \/ &hellip;","protected":false},"author":2,"featured_media":39174,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/fullwidth-template.php","meta":{"footnotes":""},"class_list":["post-10840","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"rankMath":{"parentDomain":"furnitureroots.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":true,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"restaurant-furniture","permalinkFormat":"https:\/\/furnitureroots.com\/es\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/furnitureroots.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"Restaurant Furniture You'll Love | FurnitureRoots","description":"Restaurant furniture you'll love! Buy chairs, booths, sofas &amp; tables in wood &amp; metal directly from a manufacturer providing you substantial savings. Commercial and contract grade restaurant furniture factory manufacturing custom made and bespoke restaurant furniture that are supplied globally at unbelievably low prices. FurnitureRoots - the best rated restaurant furniture suppliers &amp; manufacturers of wholesale commercial diner, bistro &amp; outdoor furniture for restaurant, cafe and bar. Get in touch with us today for quotes on your selected customized restaurant design styles.","focusKeywords":"Restaurant Furniture","pillarContent":false,"canonicalUrl":"https:\/\/furnitureroots.com\/restaurant-furniture\/","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"play","facebookAuthor":"","twitterCardType":"summary_large_image","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"play","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"Dhritiman Ranawat","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":true},"homeUrl":"https:\/\/furnitureroots.com\/es\/","objectID":10840,"objectType":"post","locale":"es","localeFull":"es_ES","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/furnitureroots.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/www\/furnitureroots_264\/public\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/furnitureroots.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/www\/furnitureroots_264\/public\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/furnitureroots.com\/wp-content\/uploads\/2018\/11\/FurnitureRoots-Site-Icon-1.png","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Ffurnitureroots.com%2Fes%2F&r=https%3A%2F%2Ffurnitureroots.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fpages%2F10840%3Fnonce%3D65adb9cfb5","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/furnitureroots.com\/wp-content\/uploads\/2020\/10\/FR-Linear-Logo-1-100x100.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/furnitureroots.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/pages\/10840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/comments?post=10840"}],"version-history":[{"count":295,"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/pages\/10840\/revisions"}],"predecessor-version":[{"id":45002,"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/pages\/10840\/revisions\/45002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/media\/39174"}],"wp:attachment":[{"href":"https:\/\/furnitureroots.com\/es\/wp-json\/wp\/v2\/media?parent=10840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}